{"id":1568024870,"date":"2020-02-26T12:29:48","date_gmt":"2020-02-26T11:29:48","guid":{"rendered":"https:\/\/settimanedellacultura.annuario.wd-bergamo.webdiocesiprod06.glauco.it\/?post_type=wd-interventi-vesc&#038;p=1568024870"},"modified":"2020-04-12T19:45:39","modified_gmt":"2020-04-12T17:45:39","slug":"mercoledi-delle-ceneri","status":"publish","type":"wd-interventi-vesc","link":"https:\/\/diocesibg.it\/settimane-della-cultura\/wd-interventi-vesc\/mercoledi-delle-ceneri\/","title":{"rendered":"Mercoled\u00ec delle Ceneri"},"excerpt":{"rendered":"<p>L\u2019inizio della Quaresima, tempo speciale, itinerario in preparazione alla celebrazione annuale della Pasqua, avviene quest\u2019anno in condizioni particolari. Il morbo chiamato \u201ccoronavirus\u201d con la sua forte disposizione al contagio, sta richiedendo interventi eccezionali sotto ogni profilo. Anche la Chiesa, in tutte le sue manifestazioni, vi \u00e8 coinvolta.<\/p>\n","protected":false},"featured_media":0,"template":"","tags":[],"wd-tipo-interventi-vesc":[367],"acf":[],"_links":{"self":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/wd-interventi-vesc\/1568024870"}],"collection":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/wd-interventi-vesc"}],"about":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/types\/wd-interventi-vesc"}],"wp:attachment":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/media?parent=1568024870"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/tags?post=1568024870"},{"taxonomy":"wd-tipo-interventi-vesc","embeddable":true,"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/wd-tipo-interventi-vesc?post=1568024870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}