{"id":1553275509,"date":"2013-03-30T10:10:00","date_gmt":"2013-03-30T09:10:00","guid":{"rendered":"https:\/\/settimanedellacultura.annuario.wd-bergamo.webdiocesiprod06.glauco.it\/wd-interventi-vesc\/sabato-santo-veglia-pasquale-2\/"},"modified":"2013-03-30T10:10:00","modified_gmt":"2013-03-30T09:10:00","slug":"sabato-santo-veglia-pasquale-2","status":"publish","type":"wd-interventi-vesc","link":"https:\/\/diocesibg.it\/settimane-della-cultura\/wd-interventi-vesc\/sabato-santo-veglia-pasquale-2\/","title":{"rendered":"Sabato Santo &#8211; Veglia Pasquale"},"excerpt":{"rendered":"<p>Cari fratelli e sorelle, \u00a0 questa veglia \u00e8 ricchissima di segni, li stiamo riconoscendo e ritrovando, come il segno della luce e il segno dell\u2019acqua. Questa veglia \u00e8 ricchissima di parole, le parole del Signore che abbiamo udito. \u00c8 ricchissima dei doni che ci consegna e che culminano nell\u2019Eucaristia. \u00a0 \u00c8 ricchissima di quella grazia particolare che questa sera il Signore consegna a questi nostri &hellip; <a href=\"https:\/\/diocesibg.it\/settimane-della-cultura\/wd-interventi-vesc\/sabato-santo-veglia-pasquale-2\/\" class=\"more-link\">Continua a leggere <span class=\"screen-reader-text\">Sabato Santo &#8211; Veglia Pasquale<\/span> <span class=\"meta-nav\">&raquo;<\/span><\/a><\/p>\n","protected":false},"featured_media":0,"template":"","tags":[],"wd-tipo-interventi-vesc":[360],"acf":[],"_links":{"self":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/wd-interventi-vesc\/1553275509"}],"collection":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/wd-interventi-vesc"}],"about":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/types\/wd-interventi-vesc"}],"wp:attachment":[{"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/media?parent=1553275509"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/tags?post=1553275509"},{"taxonomy":"wd-tipo-interventi-vesc","embeddable":true,"href":"https:\/\/diocesibg.it\/settimane-della-cultura\/wp-json\/wp\/v2\/wd-tipo-interventi-vesc?post=1553275509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}